{"id":42767,"date":"2026-01-31T14:40:57","date_gmt":"2026-01-31T13:40:57","guid":{"rendered":"https:\/\/www.frasicelebri.it\/news\/?p=42767"},"modified":"2026-03-04T16:51:02","modified_gmt":"2026-03-04T15:51:02","slug":"la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere","status":"publish","type":"post","link":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/","title":{"rendered":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-concita-de-gregorio-sul-tradimento\/\" target=\"_blank\" rel=\"noopener\">Concita De Gregorio<\/a> non \u00e8 soltanto la giornalista nota a tutti: prima di tutto \u00e8 una donna capace di parlare con sincerit\u00e0, mettendo a nudo quelle abitudini che ci rendono umani, troppo umani, come il <strong>bisogno di giudicare gli altri<\/strong>. Giudicare \u00e8 incredibilmente semplice e ci fa sentire potenti: ci illudiamo di poter parlare a testa alta di ci\u00f2 che non ci riguarda, convinti di sapere pi\u00f9 di quanto realmente sappiamo. E invece, come lei stessa ci ricorda:<\/p>\n<blockquote><p>\u201c<em>Non si tocca la vita personale delle persone, perch\u00e9 non sai mai chi hai di fronte, non conosci la sua storia, la sua ferita, il suo danno<\/em>.\u201d<\/p><\/blockquote>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-42780\" src=\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere\" width=\"1200\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>Cos\u2019\u00e8 il giudizio per Concita De Gregorio<\/h2>\n<blockquote><p>\u201cT<em>utti abbiamo un guasto, una fragilit\u00e0, un senso di non adeguatezza, e nessuno vuole essere giudicato.<\/em>\u201d<\/p><\/blockquote>\n<p>Queste parole sono vere, soprattutto nella parte finale. Tutti noi vorremmo attraversare indenni la dogana del giudizio, eppure, spesso, ci concediamo il lusso di giudicare gli altri. Lo facciamo in modo tagliente, a volte senza nemmeno rendercene conto. Ma perch\u00e9 lo facciamo? Perch\u00e9 sappiamo? No. Perch\u00e9, <strong>in quei pochi secondi in cui la lingua corre pi\u00f9 veloce del cervello,<\/strong> <strong>ci sentiamo migliori<\/strong>.<\/p>\n<p>Ma ci siamo mai chiesti cosa sappiamo davvero di una situazione che non ci appartiene? \u00c8 proprio questo il messaggio di Concita De Gregorio quando afferma:<\/p>\n<blockquote><p>\u201c<em>Non puoi giudicare la vita delle altre persone, perch\u00e9 non puoi sapere perch\u00e9 le cose sono andate in quel modo o non sono andate come avrebbero voluto<\/em>.\u201d<\/p><\/blockquote>\n<p>Concita De Gregorio non parla mai a caso: le sue parole sono sempre misurate e ci invitano a riflettere. Ci ricordano, come in questa frase, che dobbiamo esprimerci con umilt\u00e0 e rispetto verso la vita altrui. <strong>Non possiamo giudicare le scelte, l\u2019esistenza o il modo di agire degli altri perch\u00e9, in fondo, cosa ne sappiamo davvero di come sono andate le cose?<\/strong> Conosciamo davvero le ragioni che hanno influenzato quelle decisioni?<\/p>\n<h3>Non giudicare mai senza sapere (o non giudicare affatto)<\/h3>\n<p>Concita De Gregorio ci invita soprattutto a non riprendere quella lente d\u2019ingrandimento dimenticata nel cassetto, pronta a ingigantire difetti e scelte altrui senza conoscerne le ragioni. La vita di ciascuno \u00e8, infatti, modellata da contesti e condizioni diversi, da scelte e anche da errori. Se non sappiamo perch\u00e9 qualcosa \u00e8 andato in un certo modo, \u00e8 pi\u00f9 giusto <strong>adottare un atteggiamento comprensivo<\/strong> piuttosto che giudicante.<\/p>\n<p>\u00c8 preferibile fermarsi a osservare e cercare di comprendere, anzich\u00e9 puntare il dito. <strong>Meglio offrire <\/strong><a href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-oscar-wilde-sulla-gentilezza-utili-per-spiegare-ai-mariti-burberi-come-ci-si-comporta-con-le-proprie-mogli\/\" target=\"_blank\" rel=\"noopener\">gentilezza<\/a><strong> invece di condanna<\/strong>\u00a0perch\u00e9, tornando al punto di partenza, nessuno \u00e8 perfetto o completo: tutti abbiamo qualcosa che non funziona al meglio.<\/p>\n<p>Leggi altre <a href=\"https:\/\/www.frasicelebri.it\/frasi-di\/concita-de-gregorio\/\" target=\"_blank\" rel=\"noopener\">frasi celebri di Concita De Gregorio<\/a> e le <a href=\"https:\/\/www.frasicelebri.it\/argomento\/giudicare\/\" target=\"_blank\" rel=\"noopener\">frasi celebri sul giudizio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concita De Gregorio non \u00e8 soltanto la giornalista nota a tutti: prima di tutto \u00e8 una donna capace di parlare con sincerit\u00e0, mettendo a nudo &#8230; <a title=\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;\" class=\"read-more\" href=\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\" aria-label=\"More on La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;\">Leggi tutto<\/a><\/p>\n","protected":false},"author":14,"featured_media":42780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[676],"tags":[1482,1438],"class_list":["post-42767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spettacolo","tag-concita-de-gregorio","tag-frasi-sul-giudizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &quot;Non puoi conoscere la vita delle persone&quot;-Frasicelebri.it<\/title>\n<meta name=\"description\" content=\"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &quot;Non puoi conoscere la vita delle persone&quot;-Frasicelebri.it\" \/>\n<meta property=\"og:description\" content=\"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\" \/>\n<meta property=\"og:site_name\" content=\"Frasicelebri.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T13:40:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T15:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sara Bellanza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara Bellanza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\"},\"author\":{\"name\":\"Sara Bellanza\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/87eed277b0405441e405668e9452c547\"},\"headline\":\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;\",\"datePublished\":\"2026-01-31T13:40:57+00:00\",\"dateModified\":\"2026-03-04T15:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1\",\"keywords\":[\"Concita De Gregorio\",\"frasi sul giudizio\"],\"articleSection\":[\"Spettacolo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\",\"name\":\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: \\\"Non puoi conoscere la vita delle persone\\\"-Frasicelebri.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2026-01-31T13:40:57+00:00\",\"dateModified\":\"2026-03-04T15:51:02+00:00\",\"description\":\"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare\",\"breadcrumb\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800,\"caption\":\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.frasicelebri.it\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#website\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/\",\"name\":\"Frasicelebri.it\",\"description\":\"News Frasicelebri.it\",\"publisher\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.frasicelebri.it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\",\"name\":\"Frasicelebri.it\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1\",\"width\":696,\"height\":696,\"caption\":\"Frasicelebri.it\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/87eed277b0405441e405668e9452c547\",\"name\":\"Sara Bellanza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/09a3eae84da984b800b521a167211390?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/09a3eae84da984b800b521a167211390?s=96&d=mm&r=g\",\"caption\":\"Sara Bellanza\"},\"url\":\"https:\/\/www.frasicelebri.it\/news\/author\/sara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: \"Non puoi conoscere la vita delle persone\"-Frasicelebri.it","description":"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/","og_locale":"it_IT","og_type":"article","og_title":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: \"Non puoi conoscere la vita delle persone\"-Frasicelebri.it","og_description":"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare","og_url":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/","og_site_name":"Frasicelebri.it","article_published_time":"2026-01-31T13:40:57+00:00","article_modified_time":"2026-03-04T15:51:02+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg","type":"image\/jpeg"}],"author":"Sara Bellanza","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sara Bellanza","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#article","isPartOf":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/"},"author":{"name":"Sara Bellanza","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/87eed277b0405441e405668e9452c547"},"headline":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;","datePublished":"2026-01-31T13:40:57+00:00","dateModified":"2026-03-04T15:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/"},"wordCount":452,"publisher":{"@id":"https:\/\/www.frasicelebri.it\/news\/#organization"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1","keywords":["Concita De Gregorio","frasi sul giudizio"],"articleSection":["Spettacolo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/","url":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/","name":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: \"Non puoi conoscere la vita delle persone\"-Frasicelebri.it","isPartOf":{"@id":"https:\/\/www.frasicelebri.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1","datePublished":"2026-01-31T13:40:57+00:00","dateModified":"2026-03-04T15:51:02+00:00","description":"La vita \u00e8 fatta di scelte ed errori. Se non sappiamo perch\u00e9 \u00e8 successo, \u00e8 meglio comprendere e osservare, non giudicare","breadcrumb":{"@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#primaryimage","url":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/concita-de-gregorio.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800,"caption":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frasicelebri.it\/news\/la-frase-di-concita-de-gregorio-che-demolisce-chi-giudica-senza-sapere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.frasicelebri.it\/news\/"},{"@type":"ListItem","position":2,"name":"La frase di Concita De Gregorio che demolisce chi giudica senza sapere: &#8220;Non puoi conoscere la vita delle persone&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.frasicelebri.it\/news\/#website","url":"https:\/\/www.frasicelebri.it\/news\/","name":"Frasicelebri.it","description":"News Frasicelebri.it","publisher":{"@id":"https:\/\/www.frasicelebri.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frasicelebri.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.frasicelebri.it\/news\/#organization","name":"Frasicelebri.it","url":"https:\/\/www.frasicelebri.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1","width":696,"height":696,"caption":"Frasicelebri.it"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/87eed277b0405441e405668e9452c547","name":"Sara Bellanza","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/09a3eae84da984b800b521a167211390?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09a3eae84da984b800b521a167211390?s=96&d=mm&r=g","caption":"Sara Bellanza"},"url":"https:\/\/www.frasicelebri.it\/news\/author\/sara\/"}]}},"_links":{"self":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/comments?post=42767"}],"version-history":[{"count":9,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42767\/revisions"}],"predecessor-version":[{"id":42898,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42767\/revisions\/42898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/media\/42780"}],"wp:attachment":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/media?parent=42767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/categories?post=42767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/tags?post=42767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}