{"id":42885,"date":"2026-02-02T17:40:39","date_gmt":"2026-02-02T16:40:39","guid":{"rendered":"https:\/\/www.frasicelebri.it\/news\/?p=42885"},"modified":"2026-01-30T15:46:43","modified_gmt":"2026-01-30T14:46:43","slug":"frasi-di-sandra-mondaini-sul-tradimento","status":"publish","type":"post","link":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/","title":{"rendered":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace"},"content":{"rendered":"<p><strong>Sandra Mondaini<\/strong> non \u00e8 stata solo una delle attrici pi\u00f9 amate della televisione italiana: era anche una donna capace di affrontare temi delicati come l\u2019amore, il matrimonio e\u2026 <strong>le corna<\/strong>, con leggerezza, ironia e una saggezza sorprendente. In un mondo dove spesso <a href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-agnese-scappini-sul-tradimento\/#:~:text=Scappini%20sul%20tradimento-,%E2%80%9CIl%20loro%20tradimento%20non%20ha%20spezzato%20te%2C%20ha%20spezzato%20chi,e%20preferisci%20non%20portarlo%20affatto.%E2%80%9D\" target=\"_blank\" rel=\"noopener\">il tradimento<\/a> viene trattato come una tragedia senza fine, Sandra riusciva a strappare un sorriso, offrendo consigli preziosi su come vivere le relazioni con serenit\u00e0, anche quando il partner ci delude.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-42886\" src=\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"Frasi di Sandra Mondaini sul tradimento\" width=\"1200\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>L\u2019amore ha mille sfaccettature<\/h2>\n<p>Una delle frasi pi\u00f9 celebri di Sandra \u00e8:<\/p>\n<blockquote><p>\u201c<em>L\u2019amore ha mille sfaccettature. Se tu vuoi bene veramente a una persona, perch\u00e9 non dovresti accettare che abbia un momento di felicit\u00e0?<\/em>\u201d<\/p><\/blockquote>\n<p>Con questa frase, Sandra Mondaini ci mostra una visione dell\u2019amore libera da possessivit\u00e0 e gelosia eccessiva. Non significa chiudere gli occhi davanti a un tradimento o banalizzare il dolore, ma <strong>comprendere che amare davvero significa accettare che l\u2019altro possa avere momenti di <\/strong><a href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-paolo-bonolis-sulla-leggerezza\/\" target=\"_blank\" rel=\"noopener\">leggerezza<\/a><strong> e di debolezza<\/strong>. \u00c8 una lezione preziosa per chi vuole perdonare il partner e vivere il rapporto con serenit\u00e0, senza farsi schiacciare dal rancore.<\/p>\n<h2>Il matrimonio e le corna: un po\u2019 di ironia<\/h2>\n<p>Sandra Mondaini non parlava di corna solo in astratto. Con la sua tipica ironia, diceva:<\/p>\n<blockquote><p>\u201c<em>Appena sposati un cornino non lo sopporti, dopo quarant\u2019anni di matrimonio gi\u00e0 se ti mette un cornino vuol dire che \u00e8 vivo<\/em>.\u201d<\/p><\/blockquote>\n<p>In poche parole, ci ricorda che <strong>la <\/strong><a href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-osvaldo-poli-sul-dialogo-di-coppia\/\" target=\"_blank\" rel=\"noopener\">vita di coppia<\/a><strong> cambia col tempo<\/strong>. Ci\u00f2 che all\u2019inizio ci sembrava insopportabile, con gli anni pu\u00f2 diventare quasi comico, un segnale della vitalit\u00e0 del partner e del rapporto. Il matrimonio, secondo Sandra Mondaini, non \u00e8 un dogma rigido, ma un percorso da affrontare con leggerezza e senso dell\u2019umorismo.<\/p>\n<h3>Dopo le corna, la serenit\u00e0<\/h3>\n<p>Un\u2019altra frase che fa capire bene la sua filosofia \u00e8:<\/p>\n<blockquote><p>\u201c<em>Dopo le corna vengono a casa un po\u2019 pi\u00f9 stupidini, tutti contenti\u2026 e la casa \u00e8 pi\u00f9 serena<\/em>.\u201d<\/p><\/blockquote>\n<p>Sandra Mondaini ci invita a <strong>vedere il lato umano e fragile dei momenti di <\/strong><a href=\"https:\/\/www.frasicelebri.it\/argomento\/debolezza\/\" target=\"_blank\" rel=\"noopener\">debolezza<\/a>. A volte, il tradimento non segna la fine della relazione, ma pu\u00f2 essere l\u2019occasione per ridere dei drammi, per recuperare equilibrio e vivere insieme una nuova serenit\u00e0. L\u2019ironia diventa quindi uno strumento di sopravvivenza e di rinforzo della coppia.<\/p>\n<p>Per Sandra<strong>, l\u2019amore vero sa perdonare, sa ridere dei drammi e accetta le imperfezioni del partner<\/strong>. Questo approccio ci insegna che perdonare non significa rinunciare, ma scegliere la serenit\u00e0 e il benessere della coppia.<\/p>\n<h3>Amare significa anche comprendere e accettare<\/h3>\n<p>Sandra Mondaini non \u00e8 stata solo un\u2019icona della televisione italiana: \u00e8 stata una maestra di saggezza comica e di amore realistico. Le sue riflessioni sul tradimento e sulle corna ci ricordano che la vita di coppia \u00e8 fatta di sfumature, che <strong>ridere dei drammi \u00e8 spesso la miglior medicina<\/strong>, e che <strong>perdonare pu\u00f2 riportare leggerezza e serenit\u00e0 nel rapporto<\/strong>. Grazie a lei, impariamo che amare significa accettare, comprendere e, ogni tanto, sorridere anche quando il partner combina qualche pasticcio amoroso.<\/p>\n<p>Leggi altre <a href=\"https:\/\/www.frasicelebri.it\/frasi-di\/sandra-mondaini\/\" target=\"_blank\" rel=\"noopener\">frasi celebri di Sandra Mondaini<\/a> e le <a href=\"https:\/\/www.frasicelebri.it\/argomento\/tradimento\/\" target=\"_blank\" rel=\"noopener\">frasi celebri sul tradimento<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sandra Mondaini non \u00e8 stata solo una delle attrici pi\u00f9 amate della televisione italiana: era anche una donna capace di affrontare temi delicati come l\u2019amore, &#8230; <a title=\"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace\" class=\"read-more\" href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\" aria-label=\"More on Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace\">Leggi tutto<\/a><\/p>\n","protected":false},"author":12,"featured_media":42886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[676],"tags":[1541,1727],"class_list":["post-42885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spettacolo","tag-frasi-sul-tradimento","tag-sandra-mondaini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it<\/title>\n<meta name=\"description\" content=\"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it\" \/>\n<meta property=\"og:description\" content=\"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Frasicelebri.it\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T16:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Romina Cardia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Romina Cardia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\"},\"author\":{\"name\":\"Romina Cardia\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/712303166008dc510236daeaf8087292\"},\"headline\":\"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace\",\"datePublished\":\"2026-02-02T16:40:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1\",\"keywords\":[\"frasi sul tradimento\",\"Sandra Mondaini\"],\"articleSection\":[\"Spettacolo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\",\"name\":\"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2026-02-02T16:40:39+00:00\",\"description\":\"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia\",\"breadcrumb\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800,\"caption\":\"Frasi di Sandra Mondaini sul tradimento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.frasicelebri.it\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#website\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/\",\"name\":\"Frasicelebri.it\",\"description\":\"News Frasicelebri.it\",\"publisher\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.frasicelebri.it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#organization\",\"name\":\"Frasicelebri.it\",\"url\":\"https:\/\/www.frasicelebri.it\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1\",\"width\":696,\"height\":696,\"caption\":\"Frasicelebri.it\"},\"image\":{\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/712303166008dc510236daeaf8087292\",\"name\":\"Romina Cardia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7e155e0e5584fd17310efae2dc94f61e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7e155e0e5584fd17310efae2dc94f61e?s=96&d=mm&r=g\",\"caption\":\"Romina Cardia\"},\"url\":\"https:\/\/www.frasicelebri.it\/news\/author\/romina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it","description":"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/","og_locale":"it_IT","og_type":"article","og_title":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it","og_description":"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia","og_url":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/","og_site_name":"Frasicelebri.it","article_published_time":"2026-02-02T16:40:39+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Romina Cardia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Romina Cardia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#article","isPartOf":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/"},"author":{"name":"Romina Cardia","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/712303166008dc510236daeaf8087292"},"headline":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace","datePublished":"2026-02-02T16:40:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/"},"wordCount":518,"publisher":{"@id":"https:\/\/www.frasicelebri.it\/news\/#organization"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1","keywords":["frasi sul tradimento","Sandra Mondaini"],"articleSection":["Spettacolo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/","url":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/","name":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace - Frasicelebri.it","isPartOf":{"@id":"https:\/\/www.frasicelebri.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1","datePublished":"2026-02-02T16:40:39+00:00","description":"La grande Sandra Mondaini, icona della televisione italiana, ci insegna a guardare il tradimento con un sorriso e un pizzico di filosofia","breadcrumb":{"@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#primaryimage","url":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2026\/01\/sandra-mondaini.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800,"caption":"Frasi di Sandra Mondaini sul tradimento"},{"@type":"BreadcrumbList","@id":"https:\/\/www.frasicelebri.it\/news\/frasi-di-sandra-mondaini-sul-tradimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.frasicelebri.it\/news\/"},{"@type":"ListItem","position":2,"name":"Frasi di Sandra Mondaini sul tradimento, riuscirai a perdonare il partner che ti ha messo le corna e vivrete in pace"}]},{"@type":"WebSite","@id":"https:\/\/www.frasicelebri.it\/news\/#website","url":"https:\/\/www.frasicelebri.it\/news\/","name":"Frasicelebri.it","description":"News Frasicelebri.it","publisher":{"@id":"https:\/\/www.frasicelebri.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frasicelebri.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.frasicelebri.it\/news\/#organization","name":"Frasicelebri.it","url":"https:\/\/www.frasicelebri.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.frasicelebri.it\/news\/wp-content\/uploads\/2024\/07\/logo-quadrato-drasicelebri.it_.jpg?fit=696%2C696&ssl=1","width":696,"height":696,"caption":"Frasicelebri.it"},"image":{"@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/712303166008dc510236daeaf8087292","name":"Romina Cardia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.frasicelebri.it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7e155e0e5584fd17310efae2dc94f61e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e155e0e5584fd17310efae2dc94f61e?s=96&d=mm&r=g","caption":"Romina Cardia"},"url":"https:\/\/www.frasicelebri.it\/news\/author\/romina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/comments?post=42885"}],"version-history":[{"count":2,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42885\/revisions"}],"predecessor-version":[{"id":42903,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/posts\/42885\/revisions\/42903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/media\/42886"}],"wp:attachment":[{"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/media?parent=42885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/categories?post=42885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frasicelebri.it\/news\/wp-json\/wp\/v2\/tags?post=42885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}